﻿{"id":328458,"date":"2017-02-03T14:00:57","date_gmt":"2017-02-03T16:00:57","guid":{"rendered":"https:\/\/sites.arq.ufmg.br\/ea\/?p=328458"},"modified":"2017-02-03T14:06:26","modified_gmt":"2017-02-03T16:06:26","slug":"11a-edicao-do-festival-de-verao","status":"publish","type":"post","link":"https:\/\/www.arq.ufmg.br\/ea\/11a-edicao-do-festival-de-verao\/","title":{"rendered":"11\u00aa edi\u00e7\u00e3o do Festival de Ver\u00e3o"},"content":{"rendered":"<h1 class=\"page-title\">Site da 11\u00aa edi\u00e7\u00e3o do Festival de Ver\u00e3o<\/h1>\n<p>&nbsp;<br \/>\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/sites.arq.ufmg.br\/ea\/wp-content\/uploads\/2017\/02\/IMAGEM-Site-do-Festival-480-x-260.png\" alt=\"Festival de Ver\u00e3o 2017\" width=\"480\" height=\"260\" class=\"aligncenter size-full wp-image-328463\" srcset=\"https:\/\/www.arq.ufmg.br\/ea\/wp-content\/uploads\/2017\/02\/IMAGEM-Site-do-Festival-480-x-260.png 480w, https:\/\/www.arq.ufmg.br\/ea\/wp-content\/uploads\/2017\/02\/IMAGEM-Site-do-Festival-480-x-260-300x163.png 300w, https:\/\/www.arq.ufmg.br\/ea\/wp-content\/uploads\/2017\/02\/IMAGEM-Site-do-Festival-480-x-260-250x135.png 250w, https:\/\/www.arq.ufmg.br\/ea\/wp-content\/uploads\/2017\/02\/IMAGEM-Site-do-Festival-480-x-260-150x81.png 150w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><br \/>\nJ\u00e1 pode ser acessado o <a href=\"https:\/\/www.ufmg.br\/festivaldeverao\/\">hotsite do 11\u00ba Festival de Ver\u00e3o da UFMG<\/a>, que ser\u00e1 realizado de 20 a 23 de fevereiro no Centro Cultural, no Conservat\u00f3rio e no Espa\u00e7o do Conhecimento UFMG.<\/p>\n<p>Al\u00e9m de informa\u00e7\u00f5es conceituais sobre o evento e a sua programa\u00e7\u00e3o, que conta com oficinas, palestras e eventos culturais, a p\u00e1gina resgata a hist\u00f3ria do festival em todas as suas 10 edi\u00e7\u00f5es anteriores.<\/p>\n<p>Tendo como mote o tema <em>Universos (In)vis\u00edveis<\/em>, o Festival de Ver\u00e3o 2017 p\u00f5e em evid\u00eancia aspectos da realidade que, apesar de acess\u00edveis aos nossos olhos, se tornam, de alguma forma, invis\u00edveis, como a mis\u00e9ria.<\/p>\n<p>As inscri\u00e7\u00f5es para as oficinas poder\u00e3o ser feitas a partir da pr\u00f3xima ter\u00e7a-feira, 7, <a href=\"http:\/\/www.cursoseeventos.ufmg.br\/CAE\/ListarCae.aspx?TipoCae=Evento#_blank\">pelo site da Fundep<\/a> ou pessoalmente, no posto instalado na Pra\u00e7a de Servi\u00e7os, no campus Pampulha, cujo atendimento ocorre das 8h \u00e0s 12h e das 13h \u00e0s 17h. Informa\u00e7\u00f5es podem ser obtidas pelo telefone (31) 3409-4220. O pre\u00e7o \u00e9 R$ 20 por oficina. As demais atividades do Festival de Ver\u00e3o s\u00e3o gratuitas.<\/p>\n<p>Not\u00edcias sobre o evento tamb\u00e9m est\u00e3o dispon\u00edveis em suas redes sociais: no <a href=\"https:\/\/www.facebook.com\/festivaldeverao\">Facebook<\/a>, no <a href=\"https:\/\/twitter.com\/festivalufmg\">Twitter<\/a> e no <a href=\"https:\/\/www.instagram.com\/festival_ufmg\/\">Instagram<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Site da 11\u00aa edi\u00e7\u00e3o do Festival de Ver\u00e3o &nbsp; J\u00e1 pode ser acessado o hotsite do 11\u00ba Festival de Ver\u00e3o da UFMG, que ser\u00e1 realizado de 20 a 23 de fevereiro no Centro Cultural, no Conservat\u00f3rio e no Espa\u00e7o do\u2026<\/p>\n<p> <a class=\"continue-reading-link\" href=\"https:\/\/www.arq.ufmg.br\/ea\/11a-edicao-do-festival-de-verao\/\"><span><\/span><i class=\"crycon-right-dir\"><\/i><\/a> <\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31],"tags":[],"class_list":["post-328458","post","type-post","status-publish","format-standard","hentry","category-ea"],"_links":{"self":[{"href":"https:\/\/www.arq.ufmg.br\/ea\/wp-json\/wp\/v2\/posts\/328458","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.arq.ufmg.br\/ea\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.arq.ufmg.br\/ea\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.arq.ufmg.br\/ea\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.arq.ufmg.br\/ea\/wp-json\/wp\/v2\/comments?post=328458"}],"version-history":[{"count":5,"href":"https:\/\/www.arq.ufmg.br\/ea\/wp-json\/wp\/v2\/posts\/328458\/revisions"}],"predecessor-version":[{"id":328464,"href":"https:\/\/www.arq.ufmg.br\/ea\/wp-json\/wp\/v2\/posts\/328458\/revisions\/328464"}],"wp:attachment":[{"href":"https:\/\/www.arq.ufmg.br\/ea\/wp-json\/wp\/v2\/media?parent=328458"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.arq.ufmg.br\/ea\/wp-json\/wp\/v2\/categories?post=328458"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.arq.ufmg.br\/ea\/wp-json\/wp\/v2\/tags?post=328458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}